{"id":17,"count":8,"description":"Litt\u00e9rature, calculs et r\u00e9flexions sur la synth\u00e8se de front d'onde.","link":"https:\/\/wfs.pixetbel.org\/index.php\/category\/ressources\/theorie-fr\/","name":"Th\u00e9orie (Fr)","slug":"theorie-fr","taxonomy":"category","parent":13,"meta":[],"_links":{"self":[{"href":"https:\/\/wfs.pixetbel.org\/index.php\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wfs.pixetbel.org\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/wfs.pixetbel.org\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/wfs.pixetbel.org\/index.php\/wp-json\/wp\/v2\/categories\/13"}],"wp:post_type":[{"href":"https:\/\/wfs.pixetbel.org\/index.php\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}